{"id":146,"date":"2020-09-09T11:13:08","date_gmt":"2020-09-09T09:13:08","guid":{"rendered":"https:\/\/gamesfactory.fr\/marsannay\/?page_id=146"},"modified":"2025-12-01T13:25:51","modified_gmt":"2025-12-01T12:25:51","slug":"escape-game-dijon","status":"publish","type":"page","link":"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/","title":{"rendered":"Prison island"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"146\" class=\"elementor elementor-146\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-726d75fe elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"726d75fe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a4fd0c3\" data-id=\"2a4fd0c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-279b727 elementor-widget elementor-widget-heading\" data-id=\"279b727\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Prison Island 2.0 \u00e0 Dijon<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4f4ebd16 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"4f4ebd16\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-16e1e86\" data-id=\"16e1e86\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d423e91 elementor-widget elementor-widget-text-editor\" data-id=\"d423e91\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les jeux d\u2019aventure vous fascinent ? Le mot Prison Island devrait alors susciter votre int\u00e9r\u00eat. Il s\u2019agit d\u2019un nouveau concept de jeu innovant et accessible \u00e0 un large public \u00e0 Dijon. Votre logique, vos r\u00e9flexes et vos 5 sens seront mis \u00e0 l\u2019\u00e9preuve dans ce Prison Island \u00e0 Dijon. Quels types d\u2019activit\u00e9 sont pr\u00e9vus ? O\u00f9 les activit\u00e9s ont-elles lieu ? Pourquoi et comment y participer ?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e83694e elementor-widget elementor-widget-video\" data-id=\"e83694e\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/gsazcO6Qr1g&quot;,&quot;start&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c770da9 elementor-widget elementor-widget-spacer\" data-id=\"c770da9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e3d4ed elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"3e3d4ed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cafda47\" data-id=\"cafda47\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b073ba8 elementor-widget elementor-widget-ucaddon_block_rouge_titre\" data-id=\"b073ba8\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_rouge_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block titre -->\n\t\t<link id='uc_ac_assets_file_block_titre_css_1681-css' href='https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/ac_assets\/custom\/block-titre.css' type='text\/css' rel='stylesheet' >\n\n\n<div class=\"block-titre\">\n\n  <div class=\"content\">\n    <h2 class=\"titre\">Une aventure<\/h2>\n    <h3 class=\"sous-titre\">In\u00e9dite \u00e0 vivre en famille<\/h3>\n    \n        \n        \n  <\/div>\t\n\n<\/div>\n<!-- end Block titre -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b0f2039\" data-id=\"b0f2039\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9369af2 elementor-widget elementor-widget-ucaddon_block_image\" data-id=\"9369af2\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block image -->\n\t\t<link id='uc_ac_assets_file_block_image_css_912-css' href='https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/ac_assets\/custom\/block-image.css' type='text\/css' rel='stylesheet' >\n\n\n<div class=\"block-image\">\n  <div class=\"bg\" style=\"background-image: url('https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2023\/12\/Prison-Island.png'); \"><\/div>\n<\/div>\n<!-- end Block image -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-21544089 elementor-section-full_width elementor-reverse-tablet elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"21544089\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7d68bf46\" data-id=\"7d68bf46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-140bd7ad elementor-widget elementor-widget-ucaddon_block_image\" data-id=\"140bd7ad\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block image -->\n\n\n<div class=\"block-image\">\n  <div class=\"bg\" style=\"background-image: url('https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2023\/12\/PI.png'); \"><\/div>\n<\/div>\n<!-- end Block image -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49e4185 elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"49e4185\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\t\t<link id='uc_ac_assets_file_block_text_css_888-css' href='https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/ac_assets\/custom\/block-text.css' type='text\/css' rel='stylesheet' >\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Prison Island 2.0 en C\u00f4te d\u2019Or<\/h2>\n  <h3 class=\"sous-titre\">Pr\u00e9sentation du Prison Island<\/h3>\n  <p class=\"description\"><p>Prison Island est un jeu d'aventure qui ressemble \u00e0 un Escape Game dont les activit\u00e9s se d\u00e9roulent \u00e0 Marsannay-la-C\u00f4te, une commune situ\u00e9e \u00e0 10 minutes de Dijon. Ce Prison Island \u00e0 Dijon dispose de nombreux caract\u00e8res uniques et excitants assurant une exp\u00e9rience inoubliable \u00e0 chaque participant.<\/p><p>\u00a0<\/p><p>Pour vivre l\u2019aventure Prison Island, il suffit de constituer des \u00e9quipes de 4 personnes. Il faut au moins 3 personnes par \u00e9quipe pour profiter d\u2019une exp\u00e9rience de jeu optimale. Notre infrastructure peut accueillir <span style=\"text-decoration: underline\"><strong>jusqu\u2019\u00e0 80 personnes<\/strong><\/span>. Mettez-vous dans la peau d\u2019un aventurier intr\u00e9pide et aidez votre \u00e9quipe \u00e0 surmonter les obstacles sur votre passage en un minimum de temps.<\/p><p><br \/>Chaque \u00e9preuve pr\u00e9sente des niveaux de difficult\u00e9 diff\u00e9rents dans ces trois domaines:<\/p><p>\u00a0<\/p><ul><li>Physique<\/li><li>Mental<\/li><li>Technique<\/li><\/ul><p>Formez une \u00e9quipe aux forces compl\u00e9mentaires et r\u00e9ussissez chaque \u00e9preuve !<\/p><p>\u00a0<\/p><p>Prison Island vous permet de partager de bons moments en famille ou entre amis. Les tarifs sont accessibles. En une heure (Pass 1 heure), les participants parviennent \u00e0 parcourir en moyenne entre 10 et 12 cellules. En optant pour un Pass 1h30, vous augmentez vos chances de r\u00e9ussir plus d\u2019\u00e9preuves.<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a909e1d elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"a909e1d\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Prison Island \u00e0 Dijon<\/h2>\n  <h3 class=\"sous-titre\">Pour quelles cat\u00e9gories d\u2019\u00e2ge ?<\/h3>\n  <p class=\"description\"><p>Toute personne \u00e2g\u00e9e de 5 ans et plus peut s\u2019inscrire et participer au Prison Island \u00e0 Dijon. La pr\u00e9sence d\u2019un <strong>accompagnateur est obligatoire<\/strong> pour les <strong>moins de 12 ans<\/strong>. Il existe des d\u00e9fis pour les participants de 5 \u00e0 77 ans de tous les niveaux, exp\u00e9rience immersive 100% garantie !<\/p><p>\u00a0<\/p><p>Prison Island est une combinaison d\u2019ingr\u00e9dients comme l'adr\u00e9naline, la r\u00e9flexion, l'activit\u00e9 physique et le travail en \u00e9quipe.<\/p><p>\u00a0<\/p><p>Afin de garantir une immersion totale dans la th\u00e9matique choisie, Games Factory a am\u00e9nag\u00e9 une surface de jeu innovante, introuvable ailleurs. Le but est de vous faire vivre une belle aventure collective comme \u00e0 la t\u00e9l\u00e9vision et qui restera dans vos pr\u00e9cieux souvenirs.<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-782aedc5 elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"782aedc5\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Une aventure en \u00e9quipe<\/h2>\n  <h3 class=\"sous-titre\">Comme \u00e0 la t\u00e9l\u00e9vision<\/h3>\n  <p class=\"description\"><p>Rassemblez vos amis et pr\u00e9parez-vous pour une aventure passionnante \u00e0 Prison Island ouverte \u00e0 tous : jeunes et moins jeunes.<\/p><p><br \/>Formez votre \u00e9quipe et venez \u00e0 bout des diff\u00e9rents d\u00e9fis dans les cellules de la prison. Mais attention, l\u2019horloge tourne\u2026<\/p><p>\u00a0<\/p><p>Coop\u00e9rez, accumulez des points et \u00e9clatez-vous. Tout est possible ! Et n\u2019oubliez pas \u2013 L\u2019\u00e9quipe a toujours besoin de vous et vous avez toujours besoin de l\u2019\u00e9quipe !<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11b5f35e\" data-id=\"11b5f35e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f9190dd elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"1f9190dd\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Vivez l'exp\u00e9rience Prison Island<\/h2>\n  <h3 class=\"sous-titre\">En famille ou entre amis <\/h3>\n  <p class=\"description\"><div class=\"uk-grid-small uk-child-width-expand uk-flex-nowrap uk-flex-middle uk-grid\"><div class=\"el-content uk-panel\"><strong>Capacit\u00e9 :<\/strong> 80 personnes<\/div><div class=\"el-content uk-panel\"><strong style=\"font-size: 16px\">Accessible<\/strong><span style=\"font-size: 16px\"> : \u00e0 tous, d\u00e8s 5 ans<\/span><\/div><div class=\"el-content uk-panel\"><strong style=\"font-size: 16px\">Nombre de cellules :<\/strong><span style=\"font-size: 16px\"> 31<\/span><\/div><div class=\"el-content uk-panel\">\u00a0<\/div><\/div><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75665de1 elementor-widget elementor-widget-heading\" data-id=\"75665de1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4 personnes maximum par \u00e9quipe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f292cf5 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"f292cf5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/gamesfactory.fr\/marsannay\/reservations\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9servation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec52c5e elementor-align-justify gf-btn elementor-widget elementor-widget-button\" data-id=\"ec52c5e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/gamesfactory.fr\/marsannay\/tarifs\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">nos tarifs<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3650e29c elementor-widget elementor-widget-ucaddon_block_image\" data-id=\"3650e29c\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block image -->\n\n\n<div class=\"block-image\">\n  <div class=\"bg\" style=\"background-image: url('https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2022\/08\/10-1.png'); \"><\/div>\n<\/div>\n<!-- end Block image -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43f11f0 elementor-widget elementor-widget-ucaddon_block_image\" data-id=\"43f11f0\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block image -->\n\n\n<div class=\"block-image\">\n  <div class=\"bg\" style=\"background-image: url('https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2022\/08\/7-1.png'); \"><\/div>\n<\/div>\n<!-- end Block image -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89969c2 elementor-widget elementor-widget-ucaddon_block_image\" data-id=\"89969c2\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block image -->\n\n\n<div class=\"block-image\">\n  <div class=\"bg\" style=\"background-image: url('https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2022\/08\/4-1.png'); \"><\/div>\n<\/div>\n<!-- end Block image -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50f64345 elementor-widget elementor-widget-ucaddon_block_rouge_titre\" data-id=\"50f64345\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_rouge_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block titre -->\n\n\n<div class=\"block-titre\">\n\n  <div class=\"content\">\n    <h2 class=\"titre\">Offrez un bon cadeau \u00e0 vos proches<\/h2>\n    <h3 class=\"sous-titre\">vente en ligne<\/h3>\n    \n          <a href=\"\/boutique-en-ligne\/\" class=\"lien\"><\/a>\n        \n          <div class=\"bg\" style=\"background-image: url('https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2020\/11\/Image1.png'); \"><\/div>\n        \n  <\/div>\t\n\n<\/div>\n<!-- end Block titre -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-509c475 elementor-button-info elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"509c475\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2022\/09\/GF-A4-Carte-fidelite-Site-Web-JPG.jpg\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CARTE DE FID\u00c9LIT\u00c9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-94223e0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"94223e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0dbbea2\" data-id=\"0dbbea2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab2cf3d elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"ab2cf3d\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Astuces pour favoriser les chances de gagner<\/h2>\n  <h3 class=\"sous-titre\">Nos astuces<\/h3>\n  <p class=\"description\"><p>Vous souhaitez mettre toutes les chances de victoire du c\u00f4t\u00e9 de votre \u00e9quipe ? Quelques principes vous seront d\u2019une grande utilit\u00e9. En premier lieu, privil\u00e9giez une tenue d\u00e9contract\u00e9e qui vous garantira un maximum de confort et de libert\u00e9 de mouvement. Une fois \u00e0 Dijon, pr\u00eat \u00e0 jouer, gardez votre objectif ultime en t\u00eate : accumuler le plus de points possible. Une seule fa\u00e7on permet de le faire: relever un maximum de d\u00e9fis avant la fin du temps imparti.<\/p><p>\u00a0<\/p><p>Favoriser l\u2019esprit d\u2019\u00e9quipe est une r\u00e8gle d\u2019or, car le succ\u00e8s est ici savour\u00e9 en groupe. Un d\u00e9fi peut solliciter les 5 sens, la force, l\u2019agilit\u00e9 ou la logique. Ainsi, pour gagner des points, tous les membres de l\u2019\u00e9quipe doivent bien communiquer entre eux et faire preuve d\u2019une bonne coordination.<\/p><p>Chaque personne est et restera unique, avec des domaines de pr\u00e9dilection et des capacit\u00e9s propres. Les plus jeunes pourront compter sur leur dynamisme et vivacit\u00e9 d\u2019esprit pour passer \u00e0 l\u2019\u00e9preuve suivante rapidement.<\/p><p>\u00a0<\/p><p>Gr\u00e2ce \u00e0 leur exp\u00e9rience, les plus vieux n\u2019auront pas beaucoup de mal \u00e0 r\u00e9soudre les \u00e9nigmes les plus difficiles. Ce qui signifie que toutes les cat\u00e9gories de personnes ont leur importance dans le jeu et la r\u00e9ussite des missions. En famille, entre amis ou entre coll\u00e8gues, relevez le d\u00e9fi de Prison Island \u00e0 Dijon<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f4f36e2 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"f4f36e2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9508ffe\" data-id=\"9508ffe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40b6478 elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"40b6478\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Des d\u00e9cors r\u00e9alistes<\/h2>\n  <h3 class=\"sous-titre\">Avec des \u00e9nigmes adapt\u00e9es<\/h3>\n  <p class=\"description\"><p>Vous \u00eates plong\u00e9s au c\u0153ur d\u2019un milieu carc\u00e9ral o\u00f9 chaque cellule a son propre d\u00e9fi. Il ne vous reste plus qu\u2019\u00e0 le r\u00e9soudre dans le temps imparti.<\/p><p>\u00a0<\/p><p>Des d\u00e9cors r\u00e9alistes avec des <a href=\"https:\/\/fr.wikipedia.org\/wiki\/%C3%89nigme\">\u00e9nigmes<\/a> adapt\u00e9es \u00e0 tous les niveaux qui feront appel \u00e0 tous vos sens !<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5c81ae elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"c5c81ae\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Les avantages d\u2019un Escape Game \u00e0 Dijon en mode Prison Island<\/h2>\n  <h3 class=\"sous-titre\">Prison Island<\/h3>\n  <p class=\"description\"><p>Vivre une aventure in\u00e9dite entre amis ou avec des membres de la famille est d\u00e9sormais possible sans d\u00e9penser une fortune pour un voyage en lieu inconnu. Dans notre structure \u00e0 Marsannay-la-C\u00f4te, une commune localis\u00e9e \u00e0 c\u00f4t\u00e9 de Dijon, 31 cellules ont \u00e9t\u00e9 am\u00e9nag\u00e9es sp\u00e9cialement pour vous permettre d\u2019assouvir votre soif de d\u00e9fis et d\u2019aventures.<\/p><p>\u00a0<\/p><p>A Prison Island, chaque cellule vous r\u00e9serve une \u00e9preuve et un temps d\u00e9fini pour la passer. Les d\u00e9fis qui vous attendent sont vari\u00e9s et peuvent solliciter diff\u00e9rentes qualit\u00e9s de votre \u00e9quipe: r\u00e9flexion, adresse, \u00e9quilibre, astuces, etc. Vous aurez besoin de tous vos sens pour vous en sortir efficacement.<\/p><p>Afin de vous offrir la meilleure exp\u00e9rience de jeu possible, Games Factory a cr\u00e9\u00e9 des d\u00e9cors ultra r\u00e9alistes et choisi des \u00e9nigmes innovantes et r\u00e9ellement divertissantes. Enfants, jeunes et adultes trouveront leur bonheur au milieu des \u00e9preuves du meilleur Prison Island \u00e0 Dijon.<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-54c175d elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"54c175d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-679d20b\" data-id=\"679d20b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59d2eed elementor-widget elementor-widget-ucaddon_block_rouge_titre\" data-id=\"59d2eed\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_rouge_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block titre -->\n\n\n<div class=\"block-titre\">\n\n  <div class=\"content\">\n    <h2 class=\"titre\">Une solution id\u00e9ale pour un team building \u00e0 Dijon<\/h2>\n    <h3 class=\"sous-titre\">Team building<\/h3>\n    \n        \n        \n  <\/div>\t\n\n<\/div>\n<!-- end Block titre -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-672870b\" data-id=\"672870b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97f80b0 elementor-widget elementor-widget-text-editor\" data-id=\"97f80b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le team building est aujourd\u2019hui une pratique tr\u00e8s courante au sein des entreprises. Il aide \u00e0 d\u00e9velopper l\u2019esprit d\u2019\u00e9quipe et offre de nombreux autres avantages. Gr\u00e2ce \u00e0 une bonne coh\u00e9sion des collaborateurs, l\u2019ambiance au travail est plus agr\u00e9able, les risques d\u2019apparition de conflits sont limit\u00e9s. Le team building a aussi des effets boostant la productivit\u00e9.<\/p><p>Prison Island figure parmi les meilleures options \u00e0 envisager pour un team building. Dans ce sens, il faut savoir que Prison Island constitue une solution pas ch\u00e8re permettant aux entreprises de toutes les tailles de d\u00e9velopper le sentiment d\u2019appartenance et renforcer la solidarit\u00e9 chez leurs salari\u00e9s.<\/p><p>Faciliter l\u2019int\u00e9gration de nouvelles recrues devient facile, gr\u00e2ce \u00e0 une activit\u00e9 comme les Escape Games. En effet, chaque employ\u00e9 nouvellement int\u00e9gr\u00e9 profite d\u2019une opportunit\u00e9 parfaite pour faire connaissance avec ses nouveaux coll\u00e8gues. La communication s\u2019effectue d\u2019une mani\u00e8re plus d\u00e9tendue, dans un cadre loin du lieu de travail.<\/p><p>Chaque d\u00e9fi de Prison Island a \u00e9t\u00e9 choisi afin d\u2019inciter les membres d\u2019une \u00e9quipe de participants \u00e0 bien communiquer. Sans cette bonne communication, les membres de votre \u00e9quipe auront moins de chance de r\u00e9ussir les \u00e9preuves. Les jeux d\u2019\u00e9vasion permettent d\u2019une mani\u00e8re g\u00e9n\u00e9rale, d\u2019instaurer des relations de confiance entre les membres d\u2019un groupe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-56b4c47b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"56b4c47b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-35da19a2\" data-id=\"35da19a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-385fbbf elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"385fbbf\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Entrez dans l\u2019aventure<\/h2>\n  <h3 class=\"sous-titre\">de prison island<\/h3>\n  <p class=\"description\"><p>A vous de vous frayer un chemin au milieu des d\u00e9dales et des labyrinthes pour triompher \u00e0 chaque d\u00e9fi et sortir sain et sauf !<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5fd1b4da\" data-id=\"5fd1b4da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc2c7a5 elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"bc2c7a5\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Esprit d'\u00e9quipe<\/h2>\n  <h3 class=\"sous-titre\">Un pour tous et tous pour un<\/h3>\n  <p class=\"description\"><p>Esprit d\u2019\u00e9quipe, coordination, agilit\u00e9 et communication seront la clef pour que votre Team soit la meilleure et vos souvenirs inoubliables !<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5dc85ec elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5dc85ec\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-47bfc2a\" data-id=\"47bfc2a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5006d0 elementor-widget elementor-widget-ucaddon_block_image\" data-id=\"c5006d0\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block image -->\n\n\n<div class=\"block-image\">\n  <div class=\"bg\" style=\"background-image: url('https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2022\/08\/12-1.png'); \"><\/div>\n<\/div>\n<!-- end Block image -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-cf2d5fa\" data-id=\"cf2d5fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8240cfc elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"8240cfc\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Un bon programme pour un afterwork<\/h2>\n  <h3 class=\"sous-titre\">Afterwork<\/h3>\n  <p class=\"description\"><p>Afterwork est un mot anglais qui se traduit litt\u00e9ralement en \u00abapr\u00e8s le travail\u00bb. Pour les collaborateurs, l\u2019id\u00e9e est de programmer une activit\u00e9 \u00e0 faire apr\u00e8s une journ\u00e9e de travail. Cette pratique est aujourd\u2019hui adopt\u00e9e par de plus en plus d\u2019entreprises.<\/p><p>En effet, elle offre d\u2019\u00e9normes avantages, dont une meilleure coh\u00e9sion de groupe, une am\u00e9lioration de l\u2019ambiance de travail et bien d\u2019autres. Un afterwork peut \u00eatre organis\u00e9 en compl\u00e9ment d\u2019un s\u00e9minaire annuel.<\/p><p>\u00a0<\/p><p>Notre offre Prison Island \u00e0 Dijon vous donne acc\u00e8s \u00e0 un cadre exceptionnel qui aidera vos coll\u00e8gues de travail \u00e0 d\u00e9couvrir leurs talents cach\u00e9s d\u2019aventuriers.<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fab9d40 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fab9d40\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-acca31e\" data-id=\"acca31e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c73cc1 elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"5c73cc1\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">En sortir vainqueur <\/h2>\n  <h3 class=\"sous-titre\">1 cellule = 1 \u00e9preuve<\/h3>\n  <p class=\"description\"><p>Il vous faudra allier tant t\u00f4t r\u00e9flexion, \u00e9quilibre, astuces, physique et adresse pour venir \u00e0 bout des \u00e9preuves de chacune des cellules et en sortir vainqueur !<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f949e81 elementor-widget elementor-widget-ucaddon_block_image\" data-id=\"f949e81\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block image -->\n\n\n<div class=\"block-image\">\n  <div class=\"bg\" style=\"background-image: url('https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2022\/08\/17.png'); \"><\/div>\n<\/div>\n<!-- end Block image -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-401fcdc\" data-id=\"401fcdc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e173ceb elementor-widget elementor-widget-ucaddon_block_text_titre\" data-id=\"e173ceb\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_text_titre.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block text -->\n\n\n<div class=\"block-text-titre\">\n  <h2 class=\"titre\">Vous avez tous votre place dans Prison Island !<\/h2>\n  <h3 class=\"sous-titre\">De 5 \u00e0 77 ans<\/h3>\n  <p class=\"description\"><p>A chacun ses capacit\u00e9s et ses domaines de pr\u00e9dilection. Petit et agile pour se faufiler plus rapidement, sage et plein d\u2019exp\u00e9rience pour r\u00e9soudre les \u00e9nigmes les plus cors\u00e9es.\u00a0<\/p><\/p>\n<\/div>\n<!-- end Block text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60fcdb8 elementor-widget elementor-widget-ucaddon_block_image\" data-id=\"60fcdb8\" data-element_type=\"widget\" data-widget_type=\"ucaddon_block_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Block image -->\n\n\n<div class=\"block-image\">\n  <div class=\"bg\" style=\"background-image: url('https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2022\/08\/13.png'); \"><\/div>\n<\/div>\n<!-- end Block image -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Prison Island 2.0 \u00e0 Dijon Les jeux d\u2019aventure vous fascinent ? Le mot Prison Island devrait alors susciter votre int\u00e9r\u00eat. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":305,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-146","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Escape Game Dijon - Prison Island Games Factory<\/title>\n<meta name=\"description\" content=\"Prison Island est un Escape Game dont les activit\u00e9s se d\u00e9roulent \u00e0 Marsannay-la-C\u00f4te, une commune situ\u00e9e \u00e0 10 minutes de Dijon.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prison Island - Escape Game 2.0 \u00e0 Dijon\" \/>\n<meta property=\"og:description\" content=\"Prison Island est un Escape Game dont les activit\u00e9s se d\u00e9roulent \u00e0 Marsannay-la-C\u00f4te, une commune situ\u00e9e \u00e0 10 minutes de Dijon.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/\" \/>\n<meta property=\"og:site_name\" content=\"Games Factory Marsannay\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T12:25:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2021\/11\/marsa23-1-1024x819.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"819\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2021\/11\/marsa23-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/\",\"url\":\"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/\",\"name\":\"Escape Game Dijon - Prison Island Games Factory\",\"isPartOf\":{\"@id\":\"https:\/\/gamesfactory.fr\/marsannay\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2020\/10\/prison-island-1.png\",\"datePublished\":\"2020-09-09T09:13:08+00:00\",\"dateModified\":\"2025-12-01T12:25:51+00:00\",\"description\":\"Prison Island est un Escape Game dont les activit\u00e9s se d\u00e9roulent \u00e0 Marsannay-la-C\u00f4te, une commune situ\u00e9e \u00e0 10 minutes de Dijon.\",\"breadcrumb\":{\"@id\":\"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/#primaryimage\",\"url\":\"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2020\/10\/prison-island-1.png\",\"contentUrl\":\"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2020\/10\/prison-island-1.png\",\"width\":810,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/gamesfactory.fr\/marsannay\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prison island\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gamesfactory.fr\/marsannay\/#website\",\"url\":\"https:\/\/gamesfactory.fr\/marsannay\/\",\"name\":\"Games Factory Marsannay\",\"description\":\"Votre complexe de loisirs \u00e0 Marsannay\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gamesfactory.fr\/marsannay\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escape Game Dijon - Prison Island Games Factory","description":"Prison Island est un Escape Game dont les activit\u00e9s se d\u00e9roulent \u00e0 Marsannay-la-C\u00f4te, une commune situ\u00e9e \u00e0 10 minutes de Dijon.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/","og_locale":"fr_FR","og_type":"article","og_title":"Prison Island - Escape Game 2.0 \u00e0 Dijon","og_description":"Prison Island est un Escape Game dont les activit\u00e9s se d\u00e9roulent \u00e0 Marsannay-la-C\u00f4te, une commune situ\u00e9e \u00e0 10 minutes de Dijon.","og_url":"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/","og_site_name":"Games Factory Marsannay","article_modified_time":"2025-12-01T12:25:51+00:00","og_image":[{"width":1024,"height":819,"url":"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2021\/11\/marsa23-1-1024x819.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2021\/11\/marsa23-1.png","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/","url":"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/","name":"Escape Game Dijon - Prison Island Games Factory","isPartOf":{"@id":"https:\/\/gamesfactory.fr\/marsannay\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/#primaryimage"},"image":{"@id":"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/#primaryimage"},"thumbnailUrl":"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2020\/10\/prison-island-1.png","datePublished":"2020-09-09T09:13:08+00:00","dateModified":"2025-12-01T12:25:51+00:00","description":"Prison Island est un Escape Game dont les activit\u00e9s se d\u00e9roulent \u00e0 Marsannay-la-C\u00f4te, une commune situ\u00e9e \u00e0 10 minutes de Dijon.","breadcrumb":{"@id":"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/#primaryimage","url":"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2020\/10\/prison-island-1.png","contentUrl":"https:\/\/gamesfactory.fr\/marsannay\/wp-content\/uploads\/sites\/6\/2020\/10\/prison-island-1.png","width":810,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/gamesfactory.fr\/marsannay\/escape-game-dijon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/gamesfactory.fr\/marsannay\/"},{"@type":"ListItem","position":2,"name":"Prison island"}]},{"@type":"WebSite","@id":"https:\/\/gamesfactory.fr\/marsannay\/#website","url":"https:\/\/gamesfactory.fr\/marsannay\/","name":"Games Factory Marsannay","description":"Votre complexe de loisirs \u00e0 Marsannay","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gamesfactory.fr\/marsannay\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/gamesfactory.fr\/marsannay\/wp-json\/wp\/v2\/pages\/146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gamesfactory.fr\/marsannay\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gamesfactory.fr\/marsannay\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gamesfactory.fr\/marsannay\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gamesfactory.fr\/marsannay\/wp-json\/wp\/v2\/comments?post=146"}],"version-history":[{"count":227,"href":"https:\/\/gamesfactory.fr\/marsannay\/wp-json\/wp\/v2\/pages\/146\/revisions"}],"predecessor-version":[{"id":3706,"href":"https:\/\/gamesfactory.fr\/marsannay\/wp-json\/wp\/v2\/pages\/146\/revisions\/3706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gamesfactory.fr\/marsannay\/wp-json\/wp\/v2\/media\/305"}],"wp:attachment":[{"href":"https:\/\/gamesfactory.fr\/marsannay\/wp-json\/wp\/v2\/media?parent=146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}